{"id":3361,"date":"2012-07-02T15:33:43","date_gmt":"2012-07-02T15:33:43","guid":{"rendered":"http:\/\/696"},"modified":"2020-04-16T14:30:26","modified_gmt":"2020-04-16T13:30:26","slug":"svetlana-mikhaylova","status":"publish","type":"post","link":"https:\/\/ancien.siefar.org\/en\/svetlana-mikhaylova\/","title":{"rendered":"Svetlana MIKHAYLOVA"},"content":{"rendered":"<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Russie * <\/strong><a href=\"mailto:jevouslis@mail.ru\">jevouslis@mail.ru<\/a><strong><br \/> <\/strong><\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>MC * Institut des langues \u00e9trang\u00e8res\u00a0de l&#8217;Universit\u00e9 P\u00e9dagogique de la ville de Moscou (MGPU) * Histoire de la langue et de la litt\u00e9rature fran\u00e7aise, Th\u00e9orie du genre * XVIIe si\u00e8cle<\/strong><\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><em>Analyse linguistique du discours, Pragmalinguistique, Histoire de la litt\u00e9rature, Contes de f\u00e9es, Madame d\u2019Aulnoy, Histoire et \u00e9tudes du genre<\/em><\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #800000;\"><strong>ARTICLES<\/strong><\/span><br \/><span style=\"font-size: 12pt;\">&#8211;\u00a0\u00ab L&#8217;histoire de l&#8217;\u00e9ducation f\u00e9minine comme facteur de la formation de l&#8217;identit\u00e9 genr\u00e9e \u00bb, in <em>Homme. Langue. Temps<\/em>, Actes du XVIIe Colloque Skr\u00e9lina (en russe), Moscou, \u00e9d. TESAURUS, 2015, p. 264-268.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab La dominante axiologique amour comme repr\u00e9sentant linguistique de l&#8217;identit\u00e9 f\u00e9minine dans le conte de f\u00e9es f\u00e9minin \u00bb,\u00a0<em>Romania ancienne et nouvelle<\/em> (en russe), 1, 2015, p. 230-235. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">\u2013 \u00ab Jeu linguistique dans les contes de Madame d&#8217;Aulnoy \u00bb,\u00a0<em>Enseignement et apprentissage du fran\u00e7ais et du russe langues \u00e9trang\u00e8res\u00a0: parcours linguistiques et didactiques<\/em>, <em>Cahiers franco-russes de linguistique et de didactique <\/em>(Albi, \u00c9ditions multilingues \u00abFRAction\u00bb), 1, 2014, p. 51-56, <a href=\"https:\/\/www.academia.edu\/21907682\/Mikhaylova_Svetlana_JEU_LINGUISTIQUE_DANS_LES_CONTES_DE_MADAME_DAULNOY\" target=\"_blank\">en ligne<\/a>. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">\u2013 \u00ab L\u2019identit\u00e9 f\u00e9minine dans les contes de f\u00e9es fran\u00e7ais au XVIIe si\u00e8cle \u00bb, in <em>La Vie dans la langue<\/em> (en russe), Moscou, \u00e9d. Eudos, 2012, p. 414-417. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">\u2013 \u00ab La pragmatique de la Moralit\u00e9 des contes de f\u00e9es au XVIIe si\u00e8cle \u00bb, <em>Vestnik MGPU : Philologie. Th\u00e9orie de la langue. Education linguistique<\/em> (en russe), Moscou, 1, 2012, p. 29-37. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab La migration socioculturelle du genre de conte de f\u00e9es \u00bb, in <em>Theory and Practice of Social Development<\/em> (Krasnodar, www.teoria-practica.ru), 2011, <a href=\"http:\/\/www.teoria-practica.ru\/-8-2011\/philology\/mikhailova.pdf\">en ligne<\/a> (en russe). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Le th\u00e8me de l\u2019amour dans les contes de femme au XVIIe si\u00e8cle \u00bb, in <em>La Langue et la culture de France en Russie au XXIe si\u00e8cle<\/em> (en russe), Universit\u00e9 linguistique de Nijni Novgorod (NGLU), 2011, p. 217-221. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Le salon litt\u00e9raire du XVIIe si\u00e8cle comme facteur paratopique \u00bb, in <em>Vestnik MGPU : Philologie. Th\u00e9orie de la langue. Education linguistique<\/em> (en russe), Moscou, 2, 2010, p. 46-52. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Le canon esth\u00e9tique du conte de f\u00e9es f\u00e9minin au XVIIe si\u00e8cle \u00bb, in <em>L&#8217;Homme dans l&#8217;espace informatis\u00e9<\/em> (en russe), Yaroslavl, YaGPU, 2010, p. 202-207. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Les sources du conte de f\u00e9es fran\u00e7ais : Madame d\u2019Aulnoy \u00bb, in <em>Recueil des textes des jeunes chercheurs<\/em> (en russe), Moscou, MGPU, 2010, p. 126-132. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab La sp\u00e9cificit\u00e9 de la Moralit\u00e9 des contes de f\u00e9es de Madame d\u2019Aulnoy \u00bb, in <em>Le Discours linguistique dans la pratique sociale <\/em>(en russe), Tver, TGU, 2009, p. 174-178<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt; color: #800000;\"><strong>TH\u00c8SE DE DOCTORAT<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Identit\u00e9 f\u00e9minine et son objectivation dans le discours litt\u00e9raire du XVIIe sci\u00e8cle \u00bb (soutenue en 2012, \u00e0 Moscou).<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russie * jevouslis@mail.ru MC * Institut des langues \u00e9trang\u00e8res\u00a0de l&#8217;Universit\u00e9 P\u00e9dagogique de la ville de Moscou (MGPU) * Histoire de la langue et de la litt\u00e9rature fran\u00e7aise, Th\u00e9orie du genre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"categories":[16],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3361"}],"collection":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/comments?post=3361"}],"version-history":[{"count":7,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3361\/revisions"}],"predecessor-version":[{"id":5228,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3361\/revisions\/5228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media\/1933"}],"wp:attachment":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media?parent=3361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/categories?post=3361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/tags?post=3361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}