{"id":3228,"date":"2010-01-11T09:27:10","date_gmt":"2010-01-11T09:27:10","guid":{"rendered":"http:\/\/560"},"modified":"2020-04-19T12:43:18","modified_gmt":"2020-04-19T11:43:18","slug":"brigitte-rauchenbach","status":"publish","type":"post","link":"https:\/\/ancien.siefar.org\/en\/brigitte-rauchenbach\/","title":{"rendered":"Brigitte RAUCHENBACH"},"content":{"rendered":"<div class=\"corpsTexte\" style=\"text-align: justify;\"><strong><span style=\"font-size: small;\">Allemagne * <\/span><\/strong><a href=\"mailto:werausch@zedat.fu-berlin.de\"><span style=\"font-size: small;\">werausch@zedat.fu-berlin.de<\/span><\/a><strong><br \/>\n<\/strong><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><strong><br \/>\n<\/strong><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><strong><span style=\"font-size: small;\">PR * Freie Universit\u00e4t Berlin * Philosophie, Sciences politiques, XVI<sup>e<\/sup>, XVII<sup>e<\/sup>, XVIII, XIX<sup>e<\/sup>, XX<sup>e<\/sup> si\u00e8cles<\/span><\/strong><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><em><span style=\"font-size: small;\">Histoire des mentalit\u00e9s, Philosophie politique, Psychologie politique <\/span><\/em><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: small;\"><br \/>\n<span style=\"color: rgb(128, 0, 0);\"><strong>OUVRAGES<\/strong><\/span><br \/>\n&#8211; <em>Politische Philosophie und Geschlechterordnung\/ Ideengeschichte neu besehen<\/em>, in <em>Gender&#8230; politik&#8230; online<\/em>, 2004 (<a href=\"http:\/\/http :\/\/www.fu-berlin.de\/gpo\/pdf\/brigitte_rauschenbach\/brigitte_rauschenbach_.pdf\">en ligne<\/a>).<br \/>\n&#8211; <em>Der Traum und sein Schatten. Fr\u00fchfeministin und geistige Verb\u00fcndete Montaignes : Marie de Gournay und ihre Zeit, <\/em>K\u00f6nigstein\/Taunus, Ulrike Helmer Verlag, 2000.<br \/>\n&#8211; <em>Politische Philosophie und Geschlechterordnung. Eine Einf\u00fchrung,<\/em> Frankfurt am Main, Campus Verlag, 1998. <\/p>\n<p><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Allemagne * werausch@zedat.fu-berlin.de PR * Freie Universit\u00e4t Berlin * Philosophie, Sciences politiques, XVIe, XVIIe, XVIII, XIXe, XXe si\u00e8cles Histoire des mentalit\u00e9s, Philosophie politique, Psychologie politique OUVRAGES &#8211; Politische Philosophie und [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"categories":[16,1],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3228"}],"collection":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/comments?post=3228"}],"version-history":[{"count":3,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3228\/revisions"}],"predecessor-version":[{"id":8160,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3228\/revisions\/8160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media\/1933"}],"wp:attachment":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media?parent=3228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/categories?post=3228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/tags?post=3228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}