{"id":3199,"date":"2010-01-05T10:47:09","date_gmt":"2010-01-05T10:47:09","guid":{"rendered":"http:\/\/531"},"modified":"2020-04-16T14:23:21","modified_gmt":"2020-04-16T13:23:21","slug":"viviane-mellinghoff-bourgerie","status":"publish","type":"post","link":"https:\/\/ancien.siefar.org\/en\/viviane-mellinghoff-bourgerie\/","title":{"rendered":"Viviane MELLINGHOFF-BOURGERIE"},"content":{"rendered":"<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Bochum, Allemagne * <\/strong><a href=\"mailto:Viviane.E.Mellinghoff-Bourgerie@rub.de\">Viviane.E.Mellinghoff-Bourgerie@rub.de<\/a><strong><br \/> <\/strong><\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Professeure des Universit\u00e9s (jusqu&#8217;en 2009) * Ruhr-Universit\u00e4t Bochum, SACESR (Tours) * Litt\u00e9ratures Fran\u00e7aise et N\u00e9o-latine, XVIe, XVIIe si\u00e8cles<\/strong><\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><em>Direction spirituelle, \u00c9pistolaire, Impact de la tradition patristique sur les mentalit\u00e9s, Fran\u00e7ois de Sales, \u00c9rasme <\/em><\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><br \/> <span style=\"color: #800000;\"><strong>OUVRAGES<\/strong><\/span><br \/> &#8211; (avec Frieder Mellinghoff) <em>Bibliographie des Ecrivains Fran\u00e7ais : Fran\u00e7ois de Sales<\/em>, Paris\/Roma, \u00c9ditions Memini, 2007 [en part. ch. 7-10, pour les \u00ab questions f\u00e9minines \u00bb].<br \/> &#8211; <em>Fran\u00e7ois de Sales (1567-1622), un homme de lettres spirituelles. Culture, tradition, \u00e9pistolarit\u00e9<\/em> [sur sa collaboration avec Jeanne de Chantal], Gen\u00e8ve, Droz (THR 330), 1999. <\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><br \/> <span style=\"color: #800000;\"><strong>\u00c9DITION CRITIQUE<\/strong><\/span><br \/> &#8211; Gabriel Chappuys, <em>Le Secrettaire<\/em> (1588), Gen\u00e8ve, Droz (TLF 628), 2014 [\u00e9pistoli\u00e8res donn\u00e9es en mod\u00e8le au Livre V]. <\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">\u00a0<\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"color: #800000;\"><strong>ARTICLES<\/strong><\/span><br \/>&#8211; \u00ab Parole royale entre libert\u00e9 et normes \u00e9pistolaires. Autour de quelques lettres dict\u00e9es par Marguerite de Valois\u00a0\u00bb, in M.-C. Panzera &amp;\u00a0al., <em>Relier, d\u00e9lier les langues. Formes et d\u00e9fis linguistiques de la communication \u00e9pistolaire<\/em>, Bordeaux, Hermann, 2019.<\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Les Entretiens spirituels de Fran\u00e7ois de Sales\u00a0: une p\u00e9dagogie du dialogue et les avatars de sa transmission\u00a0\u00bb [sur les Visitandines en tant qu\u2019auditrices et \u00e9ditrices], in A. Cousson (dir.), <em>L\u2019Entretien au XVIIe si\u00e8cle<\/em>, Paris, Garnier, 2018, p. 97-121. <\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Autonomie de la pens\u00e9e et strat\u00e9gie du &#8220;moi&#8221; philologique : autour du <em>De conscribendis epistolis<\/em> d&#8217;Erasme et de la <em>Declaration des louenges de mariage procur\u00e9e<\/em> par Louis de Berquin \u00bb <em>(sur la valorisation \u00e9rasmienne de la femme et du mariage)<\/em>, in D. de Courcelles (dir), <em>Philologie et subjectivit\u00e9,<\/em> Paris, \u00c9cole des Chartes, 2002, p.79-98.<\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Du m\u00e9tier de moraliste \u00e0 celui de satiriste : La Bruy\u00e8re et la &#8220;machine du directeur&#8221; dans les D<em>ialogues sur le Qui\u00e9tisme<\/em> \u00bb <em>(\u00e0 propos de Mme Guyon)<\/em>, in J. Dagen (dir.), <em>Le M\u00e9tier du moraliste. Tricentenaire de la mort de La Bruy\u00e8re<\/em>, Paris, Champion, 2001, p.107-122.<\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Civilit\u00e9 als Form der christlichen Askese in den <em>Entretiens Spirituels<\/em> von Fran\u00e7ois de Sales \u00bb <em>(sur la civilit\u00e9 f\u00e9minine au clo\u00eetre)<\/em>, in W. Adam (dir.), <em>Geselligkeit und Gesellschaft im Barockzeitalter, <\/em>Wiesbaden (WAB 28), 1997, p.211-228.<\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab L&#8217;\u00e9change \u00e9pistolaire entre Marguerite de Navarre et Guillaume Bri\u00e7onnet : discours mystique ou direction spirituelle ? \u00bb, in N. Cazauran &amp; J. Dauphin\u00e9 (dir.), <em>Marguerite de Navarre (1492-1992)<\/em>, Mont-de-Marsan, \u00c9ditions InterUniversitaires, 1995, p.135-157.<\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Un entretien sans dialogue : de la correspondance de Fran\u00e7ois de Sales aux lettres spirituelles de Jean-Pierre de Caussade \u00bb <em>(probl\u00e9matique du rapport entre \u00ab directeur \u00bb et \u00ab dirig\u00e9e \u00bb)<\/em>, in B. Bray &amp; Chr. Strosetzki (dir.), <em>Art de la lettre, art de la conversation, \u00e0 l&#8217;\u00e9poque classique en France<\/em>, Paris, Klincksieck, 1995, p.179-200.<\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; \u00ab Enjeu id\u00e9ologique de la conversation et probl\u00e9matique de l&#8217;interaction sociale dans les <em>Dialogues sur le qui\u00e9tisme<\/em> de La Bruy\u00e8re \u00bb <em>(sur sa caricature de Mme Guyon)<\/em>, in A. Montandon (dir.), <em>Du go\u00fbt, de la conversation et des femmes<\/em>, Clermont-Ferrand, PU Blaise Pascal, 1994, p.91-110.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bochum, Allemagne * Viviane.E.Mellinghoff-Bourgerie@rub.de Professeure des Universit\u00e9s (jusqu&#8217;en 2009) * Ruhr-Universit\u00e4t Bochum, SACESR (Tours) * Litt\u00e9ratures Fran\u00e7aise et N\u00e9o-latine, XVIe, XVIIe si\u00e8cles Direction spirituelle, \u00c9pistolaire, Impact de la tradition patristique [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"categories":[16],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3199"}],"collection":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/comments?post=3199"}],"version-history":[{"count":5,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3199\/revisions"}],"predecessor-version":[{"id":7883,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3199\/revisions\/7883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media\/1933"}],"wp:attachment":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media?parent=3199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/categories?post=3199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/tags?post=3199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}