{"id":3190,"date":"2010-01-05T10:17:05","date_gmt":"2010-01-05T10:17:05","guid":{"rendered":"http:\/\/522"},"modified":"2020-03-09T07:34:57","modified_gmt":"2020-03-09T06:34:57","slug":"myriam-dufour-maitre","status":"publish","type":"post","link":"https:\/\/ancien.siefar.org\/en\/myriam-dufour-maitre\/","title":{"rendered":"Myriam DUFOUR-MA\u00ceTRE"},"content":{"rendered":"<p class=\"corpsTexte\" style=\"text-align: justify;\"><strong><span style=\"font-size: small;\">\u00a0<\/span><\/strong><a href=\"mailto:mdufour.maitre@wanadoo.fr\"><span style=\"font-size: small;\">mdufour.maitre@wanadoo.fr<\/span><\/a><strong> <br \/>\n <\/strong><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><strong><span style=\"font-size: small;\">retrait\u00e9e de l&#8217;Universit\u00e9 de Rouen Normandie * Universit\u00e9 de Rouen, C\u00c9R\u00c9DI \u00ab Centre d&#8217;\u00c9tudes et de Recherches \u00c9diter-Interpr\u00e9ter \u00bb *\u00a0<\/span><span style=\"font-size: small;\">Lettres, XVII<sup>e<\/sup> si\u00e8cle <\/span><\/strong><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><em><span style=\"font-size: small;\">Pr\u00e9cieuses, Femmes de lettres \u00e0 Paris et en Province, Corneille <\/span><\/em><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"color: #800000;\"><strong>OUVRAGES<\/strong><\/span><br \/>\n &#8211; <em>Michel de Pure (1620-1680), abb\u00e9 polygraphe et galant<\/em>, M. Dufour-Ma\u00eetre (dir.), Paris, Classiques Garnier (sous presse) [contributions sur les pr\u00e9cieuses, les coquettes, le mariage, etc.]<br \/>\n &#8211; <em>Les Pr\u00e9cieuses, naissance des femmes de lettres en France au XVII<sup>e<\/sup> si\u00e8cle<\/em>, Paris, H. Champion, \u00ab Lumi\u00e8re classique \u00bb, 1999. Seconde \u00e9dition : \u00ab Champion Classique Essais \u00bb, 2008. <br \/>\n &#8211; (avec Jacqueline Milhit) <em>Marie-Madeleine de La Fayette : La Princesse de Cl\u00e8ves<\/em>, Paris, Hatier, 2004 (analyse d&#8217;\u0153uvre destin\u00e9e au secondaire). <\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"color: #800000;\"><strong>\u00c9DITION CRITIQUE<\/strong><\/span><br \/>\n &#8211; Michel de Pure : <em><a href=\"http:\/\/www.siefar.org\/publications-articles\/michel-de-pure-la-precieuse-ou-le-mystere-de-la-ruelle.html\">La Pr\u00e9cieuse ou le Myst\u00e8re de la Ruelle <\/a>(1656-1660)<\/em>, Paris, H. Champion, \u00ab Sources classiques \u00bb, 2010.<br \/>\n &#8211; (avec Alain Niderst et Delphine Denis, \u00e9d.) <em>Madeleine de Scud\u00e9ry, Paul Pellisson et leurs amis : Chroniques du Samedi, suivies de pi\u00e8ces diverses<\/em>, Paris, H. Champion, \u00ab Sources classiques \u00bb, 2002. <\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: small;\"><span style=\"color: #800000;\"> <strong>ARTICLES <\/strong><\/span><\/span><\/p>\n<p class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: small;\"> &#8211; \u00ab Des &#8220;cl\u00e8res dames&#8221; aux &#8220;bas-bleus&#8221;, en passant par les &#8220;pr\u00e9cieuses&#8221; : nommer celles qui \u00e9crivent \u00bb, dans <em>Dire le genre, avec les mots, avec le corps<\/em>, Christine Bard et Fr\u00e9d\u00e9rique Le Nan (dir.), Paris, CNRS \u00c9ditions, 2019, p. 59-68.<br \/>\n &#8211; \u00ab Edmond Rostand et la pr\u00e9ciosit\u00e9 \u00bb, <em>RHLF<\/em> 118<sup>\u00e8me<\/sup> ann\u00e9e, 2018, n\u00b0 4, p. 859-871.<br \/>\n &#8211; \u00ab\u00a0Genres, signatures et attribution\u00a0: le cas de Madeleine de Scud\u00e9ry\u00a0\u00bb, dans <em>Genre et signature<\/em>, Fran\u00e7ois Regard et Anne Tomiche (dir.), Paris, Classiques Garnier, 2018, p. 173-188.<br \/>\n &#8211; \u00ab\u00a0Les pr\u00e9cieuses chansonn\u00e9es\u00a0\u00bb, dans <em>Les Plaisirs de l\u2019Arsenal. Po\u00e9sie, musique et danse aux XVII<sup>e<\/sup> et XVIII<sup>e<\/sup> si\u00e8cles<\/em>, \u00c9lise Dutray-Lecoin, Martine Lef\u00e8vre et Danielle Muzerelle (dir.), Paris, Classiques Garnier, 2018, p. 305-325.<br \/>\n &#8211; \u00ab\u00a0Des &#8220;cl\u00e8res dames&#8221; aux &#8220;bas bleus&#8221; en passant par les &#8220;pr\u00e9cieuses&#8221;\u00a0: quelles constructions de genre\u00a0?\u00a0\u00bb, in <em>Les Mots pour dire le genre<\/em>, Angers, 6 juin 2013 (sous presse).<br \/>\n &#8211; \u00ab Savoirs de soi et discours du moi dans l\u2019\u00e9change \u00e9pistolaire : l\u2019exemple de Mme de S\u00e9vign\u00e9 \u00bb, dans\u00a0<em>Raconter d&#8217;autres partages. M\u00e9langes offerts \u00e0 Nicole Jacques-Lef\u00e8vre<\/em>, sous la dir. de Christophe Martin, avec la collaboration de Jean-Christophe Abramovici, Mich\u00e8le Rosellini et Xannick Se\u00eft\u00e9, Lyon, ENS \u00c9ditions, 2017, p. 163-180.<br \/>\n &#8211; \u00ab\u00a0Galanterie, pr\u00e9ciosit\u00e9, genre\u00a0\u00bb, dans Florence Lotterie [dir.], <em>Les Voies du genre<\/em>, <em>Litt\u00e9ratures classiques<\/em>,\u00a0n\u00b090, 2016.<br \/>\n &#8211; \u00ab La critique des femmes : le cas des &#8220;pr\u00e9cieuses&#8221; \u00bb, dans Patrick Dandrey [dir.], <em>Naissance de la critique litt\u00e9raire, Litt\u00e9ratures classiques<\/em>, n\u00b0 86, 2015, p. 157-168.<br \/>\n &#8211; \u00ab &#8220;Ces Messieurs du Recueil des pi\u00e8ces choisies&#8221;. Publication collective et anonymat f\u00e9minin \u00bb, dans B\u00e9reng\u00e8re Parmentier [dir.], <em>L\u2019Anonymat de l\u2019\u0153uvre, Litt\u00e9ratures classiques<\/em> n\u00b0 80, 2013, p. 309-322.<br \/>\n &#8211; \u00ab Les pr\u00e9cieuses et les Pr\u00e9cieuses ridicules \u00bb, dans <em>Nouveaux regards sur Les Pr\u00e9cieuses ridicules, Le Nouveau Moli\u00e9riste<\/em> n\u00b0 X, 2013, p. 155-173.<br \/>\n &#8211; \u00ab La Carte de Tendre \u00bb, dans Marie-Christine Pioffet [dir.], <em>Le Dictionnaire des toponymes imaginaires dans la prose narrative de 1605 \u00e0 1712<\/em>, Presses de l\u2019Universit\u00e9 de Laval, r\u00e9\u00e9d. Paris, Hermann, &#8220;R\u00e9publique des Lettres&#8221;, 2013, p. 464-479.<br \/>\n &#8211; \u00ab H\u00e9ro\u00efnes de Corneille : des mod\u00e8les rh\u00e9toriques f\u00e9minins ? \u00bb, dans <em>Femmes, rh\u00e9torique et \u00e9loquence sous l\u2019Ancien R\u00e9gime<\/em>, Claude La Charit\u00e9 et Roxane Roy [\u00e9d.], Publications de l\u2019universit\u00e9 de Saint-\u00c9tienne, \u00ab L\u2019\u00e9cole du genre \u00bb, 2012, p. 103-110. <br \/>\n &#8211; \u00ab Oublier les Pr\u00e9cieuses ? Critique d\u2019une cat\u00e9gorie critique (1999-2009) \u00bb, dans Martine Reid [dir.], <em>Les Femmes dans la critique et l\u2019histoire litt\u00e9raire<\/em>, Paris, Honor\u00e9 Champion, \u00ab Litt\u00e9rature et genre \u00bb, 2011, p. 43-54.<br \/>\n &#8211; \u00ab &#8220;La pompe d\u2019un courroux&#8221; : \u00e9clat et mesure des \u00e9motions chez les h\u00e9ro\u00efnes tragiques de Corneille \u00bb, dans H\u00e9l\u00e8ne Merlin-Kajman [dir.],<em>\u00c9motions publiques, Litt\u00e9ratures classiques<\/em> n\u00b0 68, 2009, p. 255-270.<br \/>\n &#8211; \u00ab Les femmes de lettres, de part et d\u2019autre de l\u2019Atlantique \u00bb, dans H\u00e9l\u00e8ne Merlin-Kajman (\u00e9d.), <em>La litt\u00e9rature, le XVII<sup>e<\/sup> si\u00e8cle et nous : dialogue transatlantique, actes du colloque de Paris III (2-4 juin 2005)<\/em>, Paris, Presses de la Sorbonne Nouvelle, 2008, p. 207-219.<br \/>\n &#8211; \u00ab Une obscurit\u00e9 galante : La Pr\u00e9cieuse de Michel de Pure \u00bb, dans <em>L\u2019Obscurit\u00e9. Langage et herm\u00e9neutique sous l\u2019Ancien R\u00e9gime<\/em>, sous la dir. de Delphine Denis, Louvain, \u00c9ditions Bruylant, 2007, p. 147-157.<br \/>\n &#8211; \u00ab Sign\u00e9 : la langue ? Anonymat f\u00e9minin et repr\u00e9sentations du fran\u00e7ais dans la seconde moiti\u00e9 du XVII<sup>e<\/sup> si\u00e8cle \u00bb, dans <em>\u00c9criture, identit\u00e9, anonymat, de la Renaissance aux Lumi\u00e8res, actes du colloque de Paris X (16-17 juin 2006)<\/em>, \u00e9tudes r\u00e9unies par Nicole Jacques-Lef\u00e8vre et Marie Leca-Tsiomis, <em>Litt\u00e9rales<\/em> n\u00b0 39, Universit\u00e9 Paris X-Nanterre, 2007, p. 113-127.<br \/>\n &#8211; \u00ab Les \u00ab antipathes \u00bb : acad\u00e9mies des dames savantes et ruelles des pr\u00e9cieuses, un discours pol\u00e9mique dans l\u2019espace des Belles-Lettres \u00bb, dans <em>Bonnes lettres \/ Belles lettres, actes des colloques de Rouen (26-27 avril 2000 et 6-7 f\u00e9vrier 2003)<\/em>, r\u00e9unis par Claudine Poulouin et Jean-Claude Arnould, Paris, H. Champion, 2006, p. 271-292.<br \/>\n &#8211; \u00ab Les Pr\u00e9cieuses, de la guerre des sexes aux querelles du Parnasse : jalons d\u2019une pol\u00e9mique emp\u00each\u00e9e \u00bb, dans <em>La pol\u00e9mique au XVII<sup>e<\/sup> si\u00e8cle<\/em>, \u00e9tudes r\u00e9unies par G\u00e9rard Ferreyrolles, <em>Litt\u00e9ratures Classiques<\/em> n\u00b0 59, \u00e9t\u00e9 2006, p. 251-263.<br \/>\n &#8211; \u00ab De \u2018Pr\u00e9cieuse, \u00c9gyptienne\u2019 \u00e0 \u2018M\u00e9lisse, vieille Pr\u00e9cieuse\u2019 : naissance d\u2019un personnage, applications mondaines et ext\u00e9nuation d\u2019un type (1628-1724) \u00bb, dans <em>Le salon et la sc\u00e8ne : com\u00e9die et mondanit\u00e9 au XVII<sup>e<\/sup> si\u00e8cle<\/em>, sous la direction de Gabriel Conesa et V\u00e9ronique Sternberg, <em>Litt\u00e9ratures classiques<\/em> n\u00b0 58, printemps 2006, p. 115-130.<br \/>\n &#8211; \u00ab Eros aux flambeaux du th\u00e9\u00e2tre : enjeux des r\u00e9\u00e9critures de Psych\u00e9 pour la sc\u00e8ne (1656-1678) \u00bb, dans <em>Les M\u00e9tamorphoses de Psych\u00e9<\/em>, dossier \u00e9tabli par Carine Barbafieri et Chris Rauseo, <em>Lez Valenciennes<\/em> n\u00b0 35, Camelia, Presses Universitaires de Valenciennes, 2004, p. 41-49.<br \/>\n &#8211; \u00ab Polir l\u2019esprit en \u00e9purant le c\u0153ur : Madame de Lambert et la \u2018m\u00e9taphysique d\u2019amour\u2019 \u00bb, <em>Revue Fontenelle<\/em> n\u00b0 1, 2003, p. 119-140.<br \/>\n &#8211; \u00ab Les \u2018belles\u2019 et les Belles-Lettres : femmes, instances du f\u00e9minin et nouvelles configurations du savoir \u00bb, dans <em>Le Savoir au XVII<sup>e<\/sup> si\u00e8cle, Actes du 34e congr\u00e8s annuel de la N.A.S.S.C.F.L.<\/em>, University of Virginia, Charlottesville, 14-16 mars 2002, \u00e9dit\u00e9s par John D. Lyons et Cara Welch, T\u00fcbingen, Gunter Narr, \u00ab Biblio 17 \u00bb n\u00b0 147, 2003, p. 35-64.<br \/>\n &#8211; \u00ab La critique du mariage dans La Pretieuse de Michel de Pure \u00bb, dans <em>Le mariage dans l\u2019Europe des XVI<sup>e<\/sup> et XVII<sup>e<\/sup> si\u00e8cles : r\u00e9alit\u00e9s et repr\u00e9sentations<\/em>, textes r\u00e9unis par Richard Crescenzo, Marie-Roig Miranda et V\u00e9ronique Zaercher, Nancy, 2003, 2 vol., t. I, p. 357-370.<br \/>\n &#8211; \u00ab La Pr\u00e9cieuse de Michel de Pure : de l\u2019impossible corps des femmes \u00e0 la personne de la lectrice \u00bb, dans <em>Les femmes au Grand Si\u00e8cle ; Le Baroque : musique et litt\u00e9rature ; Musique et liturgie, Actes du 33e congr\u00e8s annuel de la North American Society for Seventeenth-Century French Literature<\/em>, tome II, Arizona State University (Tempe), May 2001, \u00e9dit\u00e9s par David Wetsel et Fr\u00e9d\u00e9ric Canovas avec la collaboration de Christine Probes et Buford Norman, T\u00fcbingen, Gunter Narr Verlag, \u00ab Biblio 17 \u00bb n\u00b0 144, 2003, p. 61-75.<br \/>\n &#8211; \u00ab Sapho reine de Tendre : entre monarchie absolue et royaut\u00e9 litt\u00e9raire \u00bb, dans <em>Madeleine de Scud\u00e9ry : une femme de lettres au XVII<sup>e<\/sup> si\u00e8cle<\/em>, \u00e9tudes r\u00e9unies par Delphine Denis et Anne-Elisabeth Spica, Artois Presses Universit\u00e9, 2002, p. 179-193.<br \/>\n &#8211; \u00ab Les escortes mondaines de la publication \u00bb, dans <em>De La Publication. Entre Renaissance et Lumi\u00e8res<\/em>, Alain Viala et Christian Jouhaud [dir.], Paris, Fayard, 2002, p. 249-265. [sur les strat\u00e9gies de publication du cercle de Madeleine de Scud\u00e9ry]<br \/>\n &#8211; \u00ab \u00c9diter, imprimer, publier : quelques strat\u00e9gies f\u00e9minines au XVII<sup>e<\/sup> si\u00e8cle \u00bb, dans <em>L\u2019\u00e9crivain \u00e9diteur<\/em>, textes r\u00e9unis par Fran\u00e7ois Bessire, Strasbourg, Travaux de Litt\u00e9rature n\u00b0 14, 2001, p. 257-276.<br \/>\n &#8211; \u00ab L\u2019amour, un geste langagier : pr\u00e9ciosit\u00e9 et politesse amoureuse chez Mlle de Scud\u00e9ry \u00bb, dans <em>La Politesse amoureuse de Marsile Ficin \u00e0 Madeleine de Scud\u00e9ry, actes du colloque du \u00ab Centre de Recherche sur les Classicismes \u00bb<\/em>, Reims, 17-19 novembre 1999, r\u00e9unis par Daniela Dalla-Valle, Franco-Italica n\u00b0 15-16, 1999, p. 163-173.<br \/>\n &#8211; \u00ab Une anti-curiosit\u00e9 : la discr\u00e9tion chez Mlle de Scud\u00e9ry \u00bb, dans <em>La Curiosit\u00e9<\/em>, sous la direction de Nicole Jacques-Chaquin et de Sophie Houdard, ENS Fontenay \/ St-Cloud, 1999, t. II, p. 333-358.<br \/>\n &#8211; \u00ab Lettres de Sapho, lettres de Madeleine. Les lettres dans la Cl\u00e9lie et la correspondance de Mlle de Scud\u00e9ry \u00bb, dans <em>L&#8217;Epistolaire, un genre f\u00e9minin ?<\/em>, sous la direction de Christine Plant\u00e9, Paris, H. Champion, 1998, p. 51-66.<br \/>\n &#8211; \u00ab La question d&#8217;amour, ou la passion fa\u00e7onn\u00e9e : l&#8217;\u00e9thique de l&#8217;esth\u00e9tique pr\u00e9cieuse \u00bb, dans <em>Passion, \u00e9motion, pathos<\/em>, textes r\u00e9unis et pr\u00e9sent\u00e9s par Anne Coudreuse et Bruno Delignon, <em>La Licorne<\/em>, UFR de Langues et Litt\u00e9ratures de l&#8217;Universit\u00e9 de Poitiers, 1997, p. 95-106.<br \/>\n <\/em><\/span><\/p>\n<p><span style=\"font-size: small;\"><span style=\"font-size: small;\"><span style=\"color: #800000;\"><strong><br \/>\n NOTICES<\/strong><\/span><br \/>\n&#8211; \u00ab\u00a0Madame de Lambert\u00a0\u00bb, dans\u00a0<em>Dictionnaire des philosophes du XVII<sup>e<\/sup> si\u00e8cle<\/em>, Paris, Classiques Garnier, 2014 p.\u00a0951-954.<br \/>\n &#8211; \u00ab Pr\u00e9cieuses \u00bb, \u00ab S\u00e9vign\u00e9 \u00bb, \u00ab La Suze \u00bb, \u00ab Lambert \u00bb, \u00ab Maintenon \u00bb, \u00ab Sabl\u00e9 \u00bb, \u00ab Br\u00e9gy \u00bb, \u00ab Montausier \u00bb, \u00ab Longueville \u00bb, \u00ab Nemours \u00bb, \u00ab Rambouillet \u00bb, \u00ab La Sabli\u00e8re \u00bb, in B. Didier (dir.), <em>Dictionnaire universel des cr\u00e9atrices<\/em>, Paris, \u00c9ditions Des Femmes, 2013.<br \/>\n &#8211; \u00ab La carte de Tendre \u00bb, in D. Maher &#038; M.-Ch. Pioffet (dir.), <em>Dictionnaire analytique des toponymes imaginaires dans la prose narrative de 1605 \u00e0 1712<\/em>, Laval, PU de Laval, 2010.<br \/>\n &#8211; \u00ab <a href=\"http:\/\/www.siefar.org\/dictionnaire\/fr\/Madeleine_de_Scud%C3%A9ry\">Scud\u00e9ry, Madeleine<\/a> \u00bb, in <em>Dictionnaire des femmes de l&#8217;Ancienne France<\/em>, SIEFAR, 2008.<\/span><\/span><\/p>\n<p><span style=\"font-size: small;\"><span style=\"font-size: small;\"><span style=\"color: #800000;\"><strong><br \/>\n DIVERS<\/strong><\/span><br \/>\n &#8211; \u00ab Les femmes en libert\u00e9 surveill\u00e9e \u00bb, <em>Magazine litt\u00e9raire sp\u00e9cial Moli\u00e8re<\/em> n\u00b0575, janvier 2017, p. 80-82.<br \/>\n &#8211; \u00ab La farce sociale d\u2019une coquette et d\u2019un barbon : Le Mariage forc\u00e9 de Moli\u00e8re (1664) \u00bb et \u00ab Moli\u00e8re et le mythe du mariage d\u2019amour \u00bb, <em>revue Mythologie(s), Moli\u00e8re<\/em>, hors-s\u00e9rie n\u00b016, septembre 2017, p. 56-61.<br \/>\n &#8211; Co-directrice de la collection \u00ab Masculin\/F\u00e9minin \u00bb, s\u00e9rie \u00ab XVII<sup>e<\/sup> si\u00e8cle \u00bb, Classiques Garnier <\/span><\/span><\/p>\n<p><span style=\"font-size: small;\"><span style=\"font-size: small;\"><span style=\"color: #800000;\"><strong><br \/>\n EMISSIONS RADIOPHONIQUES<\/strong><\/span><br \/>\n &#8211; \u00ab La Carte de Tendre \u00bb, \u00e9mission pour la <em>Radio Suisse Romande<\/em>, \u00e9t\u00e9 2007.<br \/>\n &#8211; \u00ab Une vie, une oeuvre : Mlle de Scud\u00e9ry \u00bb, \u00e9mission de Christine Go\u00e9m\u00e9, <em>France-Culture<\/em>, 15\/01\/1998.<br \/>\n &#8211; \u00ab Les chemins de la connaissance : les Pr\u00e9cieuses \u00bb, \u00e9mission de Christine Go\u00e9m\u00e9, <em>France-Culture<\/em>, 6\/10\/1997.<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0mdufour.maitre@wanadoo.fr retrait\u00e9e de l&#8217;Universit\u00e9 de Rouen Normandie * Universit\u00e9 de Rouen, C\u00c9R\u00c9DI \u00ab Centre d&#8217;\u00c9tudes et de Recherches \u00c9diter-Interpr\u00e9ter \u00bb *\u00a0Lettres, XVIIe si\u00e8cle Pr\u00e9cieuses, Femmes de lettres \u00e0 Paris et [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"categories":[16,1],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3190"}],"collection":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/comments?post=3190"}],"version-history":[{"count":13,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3190\/revisions"}],"predecessor-version":[{"id":8625,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3190\/revisions\/8625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media\/1933"}],"wp:attachment":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media?parent=3190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/categories?post=3190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/tags?post=3190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}