{"id":3121,"date":"2009-12-27T15:19:44","date_gmt":"2009-12-27T14:19:44","guid":{"rendered":"http:\/\/449"},"modified":"2020-04-15T18:03:41","modified_gmt":"2020-04-15T17:03:41","slug":"genevieve-fraisse","status":"publish","type":"post","link":"https:\/\/ancien.siefar.org\/en\/genevieve-fraisse\/","title":{"rendered":"Genevi\u00e8ve FRAISSE"},"content":{"rendered":"<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Paris, France * <\/strong><a href=\"mailto:genevieve.fraisse@orange.fr\">genevieve.fraisse@orange.fr <\/a><strong><br \/> <\/strong><\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\">\u00a0<\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><strong>Directrice de recherche * CNRS * philosophie, XVIIe, XVIIIe, XIXe, XXe si\u00e8cles <\/strong><\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">\u00a0<\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><em>Philosophie, Histoire, \u00c9galit\u00e9 des sexes, Histoire de la controverse des sexes du point de vue \u00e9pist\u00e9mologique et politique <\/em><\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><br \/> <span style=\"color: #800000;\"><strong>OUVRAGES<\/strong><\/span><br \/> <em>&#8211; La Sexuation du monde, r\u00e9flexions sur l&#8217;\u00e9mancipation<\/em>, Paris, Presses de Sciences Po, 2016. <\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211;\u00a0<em>Les Exc\u00e8s du genre\u00a0: concept, image, nudit\u00e9<\/em>, Paris, \u00c9ditions Lignes, 2014. <\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211;\u00a0<em>La Fabrique du f\u00e9minisme\u00a0: textes et entretiens<\/em>, Cong\u00e9-sur-Orne, Le Passager clandestin, 2012. <\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211;\u00a0<em>\u00c0 c\u00f4t\u00e9 du genre\u00a0: sexe et philosophie de l&#8217;\u00e9galit\u00e9<\/em>, Lormont, Le Bord de l&#8217;eau, 2010, reprise de <em>La Diff\u00e9rence des sexes<\/em>, <em>La Controverse des sexes<\/em> et autres textes. <\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; <em>Service ou servitude, essai sur les femmes toutes mains<\/em>, Lormont, Le Bord de l\u2019eau, 2009 (\u00e9d. augment\u00e9e de <em>Femmes toutes mains, essai sur le service domestique<\/em>, 1979, voir <em>infra<\/em>).<br \/><\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211;\u00a0<em>Du Consentement<\/em>, Paris, Seuil, 2007. <\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">&#8211; <em>Cl\u00e9mence Royer, philosophe et femme de sciences (1830-1902)<\/em>, Paris, La D\u00e9couverte, 1985, r\u00e9\u00e9dition 2002.<br \/> &#8211; <em>Les deux gouvernements : la famille et la cit\u00e9,<\/em> Paris, Gallimard, 2001.<br \/> &#8211; <em>La Controverse des sexes<\/em>, Paris, PUF, 2001.<br \/> &#8211; <em>Les Femmes et leur histoire<\/em>, Paris, Gallimard \u00ab Folio \u00bb, 1998 (nouvelle \u00e9d. revue 2010).<br \/> &#8211; <em>La Diff\u00e9rence des sexes<\/em>, Paris, PUF, 1996.<br \/> &#8211; <em>Muse de la Raison. D\u00e9mocratie et exclusion des femmes en France<\/em>, Aix-en-Provence, Alin\u00e9a, 1989 ; r\u00e9\u00e9d. Paris, Gallimard \u00ab Folio \u00bb, 1995.<br \/> &#8211; <em>La Raison des femmes,<\/em> Paris, Plon, 1992.<br \/> &#8211; <em>Femmes toutes mains, essai sur le service domestique,<\/em> Paris, Le Seuil, 1979.<\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"> <br \/> <span style=\"color: #800000;\"><strong>\u00c9DITIONS<\/strong><\/span><br \/> &#8211; (Pr\u00e9sentation)\u00a0Fanny Raoul : <em>Opinion d&#8217;une femme sur les femmes <\/em><em>(1801)<\/em>, Paris, Le Passager clandestin, 2011.<br \/> &#8211; (co\u00e9ditrice), <em>Histoire des femmes en Occident, Volume IV (XIXe),<\/em> dir. G. Duby &amp; M. Perrot, 1991, Plon tempus 2002.<br \/> &#8211; (Pr\u00e9face)\u00a0<em>Opinions de femmes, de la veille au lendemain de la r\u00e9volution fran\u00e7aise<\/em> (M.-A. Gacon-Dufour, O. de Gouges, C. de Salm, A. Cl\u00e9ment-H\u00e9mery, F.Raoul), Paris, C\u00f4t\u00e9-Femmes, 1989.<\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\">\u00a0<\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: 12pt;\"><span style=\"font-size: 12pt;\"><span style=\"color: #800000;\"><strong>ARTICLE<\/strong><\/span><br \/> &#8211; \u00ab Querelle, proc\u00e8s, controverse, les trois figures de la pens\u00e9e f\u00e9ministe \u00bb, in E. Viennot (dir.), <em><a href=\"http:\/\/www.siefar.org\/publications-articles\/revisiter-la-querelle-des-femmes.html\">Revisiter la \u00ab querelle des femmes \u00bb : Discours sur l\u2019\u00e9galit\u00e9\/in\u00e9galit\u00e9 des sexes, de 1750 aux lendemains de la R\u00e9volution<\/a><\/em>, Saint-Etienne, PUSE, 2012.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paris, France * genevieve.fraisse@orange.fr \u00a0 Directrice de recherche * CNRS * philosophie, XVIIe, XVIIIe, XIXe, XXe si\u00e8cles \u00a0 Philosophie, Histoire, \u00c9galit\u00e9 des sexes, Histoire de la controverse des sexes du [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"categories":[16,1],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3121"}],"collection":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/comments?post=3121"}],"version-history":[{"count":5,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3121\/revisions"}],"predecessor-version":[{"id":7657,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/3121\/revisions\/7657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media\/1933"}],"wp:attachment":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media?parent=3121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/categories?post=3121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/tags?post=3121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}