{"id":2663,"date":"2014-09-30T00:00:00","date_gmt":"2014-09-30T00:00:00","guid":{"rendered":"20777"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-30T07:00:00","slug":"attending-to-early-modern-women-it-s-about-time","status":"publish","type":"post","link":"https:\/\/ancien.siefar.org\/en\/attending-to-early-modern-women-it-s-about-time\/","title":{"rendered":"Attending to Early Modern Women: It&#8217;s About Time"},"content":{"rendered":"<p><\/em><\/multi><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":813,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"categories":[6,9],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/2663"}],"collection":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/comments?post=2663"}],"version-history":[{"count":0,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/2663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media\/813"}],"wp:attachment":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media?parent=2663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/categories?post=2663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/tags?post=2663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}