{"id":2467,"date":"2013-01-07T00:00:00","date_gmt":"2013-01-07T00:00:00","guid":{"rendered":"20576"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-30T07:00:00","slug":"recrutement-de-chercheur-euse-s","status":"publish","type":"post","link":"https:\/\/ancien.siefar.org\/en\/recrutement-de-chercheur-euse-s\/","title":{"rendered":"Recrutement de chercheur-euse-s"},"content":{"rendered":"<p><\/em><\/multi><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"categories":[6,11],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/2467"}],"collection":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/comments?post=2467"}],"version-history":[{"count":0,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/2467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media\/1575"}],"wp:attachment":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media?parent=2467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/categories?post=2467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/tags?post=2467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}