{"id":2168,"date":"2011-03-21T00:00:00","date_gmt":"2011-03-21T00:00:00","guid":{"rendered":"20266"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-30T07:00:00","slug":"pouvoirs-des-femmes-pratiques-reprsentations-effets","status":"publish","type":"post","link":"https:\/\/ancien.siefar.org\/en\/pouvoirs-des-femmes-pratiques-reprsentations-effets\/","title":{"rendered":"\u00ab Pouvoirs des femmes \u00bb Pratiques, repr\u00e9sentations, effets"},"content":{"rendered":"<p><\/em><\/multi><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"categories":[6,9],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/2168"}],"collection":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/comments?post=2168"}],"version-history":[{"count":0,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/2168\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media\/323"}],"wp:attachment":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media?parent=2168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/categories?post=2168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/tags?post=2168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}