{"id":10486,"date":"2023-04-21T09:26:36","date_gmt":"2023-04-21T08:26:36","guid":{"rendered":"http:\/\/siefar.org\/?p=10486"},"modified":"2023-04-21T09:27:24","modified_gmt":"2023-04-21T08:27:24","slug":"parution-de-notre-adherente-jennifer-tamas","status":"publish","type":"post","link":"https:\/\/ancien.siefar.org\/en\/parution-de-notre-adherente-jennifer-tamas\/","title":{"rendered":"Parution de notre adh\u00e9rente Jennifer Tamas"},"content":{"rendered":"<p><strong><a href=\"http:\/\/siefar.org\/wp-content\/uploads\/2023\/04\/au-non-des-femmes-2-3.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-10487 size-medium alignleft\" src=\"http:\/\/siefar.org\/wp-content\/uploads\/2023\/04\/au-non-des-femmes-2-3-e1682065561274-207x300.jpg\" alt=\"\" width=\"207\" height=\"300\" srcset=\"https:\/\/ancien.siefar.org\/wp-content\/uploads\/2023\/04\/au-non-des-femmes-2-3-e1682065561274-207x300.jpg 207w, https:\/\/ancien.siefar.org\/wp-content\/uploads\/2023\/04\/au-non-des-femmes-2-3-e1682065561274.jpg 345w\" sizes=\"(max-width: 207px) 100vw, 207px\" \/><\/a>Paris, Seuil, janvier 2023, 325 p., 23\u20ac<\/strong><\/p>\n<p style=\"text-align: justify;\">Rien ne semble plus incongru que de prendre appui sur la soci\u00e9t\u00e9 d\u2019Ancien R\u00e9gime pour penser le refus f\u00e9minin. Assign\u00e9es au devoir de \u00ab r\u00e9serve \u00bb par les trait\u00e9s de civilit\u00e9 et au silence ou \u00e0 la \u00ab feinte r\u00e9sistance \u00bb par les codes de s\u00e9duction, les h\u00e9ro\u00efnes de la litt\u00e9rature classique n\u2019auraient rien \u00e0 nous transmettre, surtout pas le pouvoir de dire \u00ab non \u00bb. On aurait pu croire l\u2019affaire pli\u00e9e sans la sagacit\u00e9 de Jennifer Tamas. Car, \u00e0 leur mani\u00e8re, les femmes du Grand Si\u00e8cle ont r\u00e9sist\u00e9, elles ont d\u00e9sob\u00e9i, et de ces combats \u00e0 bas bruit il demeure des traces. Sous les images de princesses endormies c\u00e9l\u00e9br\u00e9es par l\u2019industrie du divertissement se cachent de puissants refus, occult\u00e9s par des si\u00e8cles d\u2019interpr\u00e9tations patriarcales. Jennifer Tamas les exhume avec courage et subtilit\u00e9, elle traque l\u2019expression du f\u00e9minin sous le regard masculin et tend savamment l\u2019oreille vers le bruissement des voix r\u00e9calcitrantes. Conviant les figures dissidentes des si\u00e8cles anciens, du Petit Chaperon rouge \u00e0 B\u00e9r\u00e9nice, elle vivifie le discours f\u00e9ministe et trouve chez Marilyn Monroe le secret d\u2019H\u00e9l\u00e8ne de Troie. Elle r\u00e9v\u00e8le ainsi, non sans un brin d\u2019irr\u00e9v\u00e9rence, un magnifique\u00a0<i>matrimoine<\/i>, trop longtemps s\u00e9questr\u00e9 dans les forteresses universitaires.<\/p>\n<p style=\"text-align: justify;\">Jennifer Tamas est agr\u00e9g\u00e9e de lettres modernes et enseigne la litt\u00e9rature fran\u00e7aise de l\u2019Ancien R\u00e9gime aux \u00c9tats-Unis \u00e0 Rutgers University (New Jersey). Elle a notamment publi\u00e9\u00a0<i>Le Silence trahi. Racine ou la d\u00e9claration tragique<\/i>\u00a0(Droz, 2018).<\/p>\n<p><a href=\"https:\/\/www.jennifertamas.com\/au-non-des-femmes\"><strong>Site de l&#8217;autrice et revue de presse<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.seuil.com\/ouvrage\/au-non-des-femmes-jennifer-tamas\/9782021514292\"><strong>Acheter en ligne<\/strong><\/a><\/p>\n<p><strong>Rencontre avec Aurore Evain \u00e0 la <a href=\"https:\/\/www.librairieparoles.com\/\">Librairie Paroles de Saint-Mand\u00e9<\/a> le 1er juin 2023, de 19h30 \u00e0 21h<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paris, Seuil, janvier 2023, 325 p., 23\u20ac Rien ne semble plus incongru que de prendre appui sur la soci\u00e9t\u00e9 d\u2019Ancien R\u00e9gime pour penser le refus f\u00e9minin. Assign\u00e9es au devoir de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10487,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"categories":[5,7],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/10486"}],"collection":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/comments?post=10486"}],"version-history":[{"count":2,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/10486\/revisions"}],"predecessor-version":[{"id":10490,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/posts\/10486\/revisions\/10490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media\/10487"}],"wp:attachment":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media?parent=10486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/categories?post=10486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/tags?post=10486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}