{"id":2816,"date":"2009-05-23T18:18:57","date_gmt":"2009-05-23T18:18:57","guid":{"rendered":"122"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-30T07:00:00","slug":"les-mots-de-a-a-z-lettre-n","status":"publish","type":"page","link":"https:\/\/ancien.siefar.org\/en\/la-guerre-des-mots-dictionnaire\/les-mots-de-a-a-z-lettre-n\/","title":{"rendered":"Les mots de A \u00e0 Z &#8211; lettre N"},"content":{"rendered":"<ul>\n<li><strong><span style=\"font-size: small;\"><a name=\"Nomspropres\"><\/a>NOMS PROPRES<\/span><\/strong><span style=\"font-size: small;\"><br \/>\n    <\/span><\/li>\n<\/ul>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: small;\"><br \/>\n&#8211; <strong>Certains hommes prennent le nom de leur femme.<\/strong><br \/>\n&#8212; <strong>XVe si&egrave;cle<\/strong> : Guillaume de l&#8217;Aire, de Tignac dans l&#8217;Ari&egrave;ge, &laquo;prit femme &agrave; Lordat, et &agrave; cause de la famille de sa femme dans laquelle il entra, on l&#8217;appela d&eacute;sormais Guillaume de Corneillan.&raquo;<br \/>\nJean Verdon, <em>Les Fran&ccedil;aises pendant la guerre de Cent Ans<\/em>, Paris, Perrin, 1991, p.106.<br \/>\n&#8211; <strong>Certains noms de famille sont f&eacute;minis&eacute;s comme dans d&#8217;autres langues vivantes.<\/strong><br \/>\n&#8212; <strong>XVe si&egrave;cle<\/strong> : une certaine Jeanne Jourdain est nomm&eacute;e &laquo;Jourdaine&raquo; dans la lettre de r&eacute;mission qui rapporte son cas.<br \/>\nJean Verdon, <em>Les Fran&ccedil;aises pendant la guerre de Cent Ans<\/em>, p.91.<br \/>\n&#8212; <strong>1580-1582<\/strong> : Fran&ccedil;oise de Montmorency (1566-apr&egrave;s 1585), fille de Pierre de Thury, baron de Fosseux, et de Jacqueline d&#8217;Avaugour, ma&icirc;tresse du roi de Navarre, est couramment appel&eacute;e &laquo;Fosseuse&raquo; <\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: small;\">(cf. correspondance de Catherine de M&eacute;dicis, correspondance et M&eacute;moires de Marguerite de Valois&#8230;)<br \/>\n&#8212; <strong>1588 <\/strong>: &laquo;les Foucaudes br&ucirc;l&eacute;es &agrave; Paris, pour la religion. Le mardi 28e juing <em>(1588)<\/em>, par sentence du Pr&eacute;vost de Paris, confirm&eacute; par arrest de la Cour, furent pendues et puis brusl&eacute;es, en la place de Greve &agrave; Paris, deux surs parisiennes, filles de feu ma&icirc;tre Jacques Foucaud, quand il vivoit procureur au Parlement, comme Huguenotes et Heretiques des plus obstin&eacute;es et opiniastres. Partant, furent baillonn&eacute;es quand on les mena au supplice; lequel elles endur&egrave;rent fort constamment, sans se vouloir jamais desdire; tellement qu&#8217;une des deux fut brusl&eacute;e toute vifve, par la fureur du peuple anim&eacute;, qui coupa la corde avant qu&#8217;elle fut estrangl&eacute;e et la jetta dans le feu.&raquo;<br \/>\nP. de l&#8217;Estoile, <em>Registre-Journal du r&egrave;gne de Henri III<\/em>, &eacute;d. Schrenk-Lazard, vol.6, p.56.<br \/>\n&#8211; <strong>Des femmes gardent leur nom de jeune fille<\/strong><br \/>\n&#8212;<strong>XVIe s. <\/strong>: &laquo;Dans la France du 16e si&egrave;cle, les femmes gardent en g&eacute;n&eacute;ral toute la vie leur nom de jeune fille, compl&eacute;t&eacute; au besoin de la locution &laquo;femme&raquo; ou &laquo;veuve&raquo; d&#8217;un-tel. Mais certaines ont aussi un sobriquet&raquo; <\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: small;\">Natalie Davis, <em>Les Cultures du peuple. Rituels, savoirs et r&eacute;sistances au XVIe si&egrave;cle,<\/em> Paris, Aubier, 1979, p.120.<\/p>\n<p><\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><\/div>\n<ul>\n<li><span style=\"font-size: small;\"><strong><a name=\"Notaire\"><\/a>Notaire, Notaresse<\/strong><\/span><\/li>\n<\/ul>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: small;\"><br \/>\n&#8211; <strong>1622 <\/strong>: &laquo;ce fut la Procureuse, qui dit: &quot;Vraiment, la marchande qui vient de sortir a bien chang&eacute; de poil depuis qu&#8217;elle a quitt&eacute; sa boutique; la congnoissez vous bien particuli&egrave;rement, Mesdames&#8217;&quot; A cette demande personne ne voulut respondre, que la petite effet&eacute;e de Notaire, qui dict que du temps qu&#8217;elles estoit fille on en parlait fort, et qu&#8217;elle alloit la nuict trouver un certain homme pour coucher avec luy. <em>(&#8230;)<\/em> Son mary estoit donc aux champs, quand elle faisoit ce train-l&agrave;, respondit la Procureuse? Non, Madame, luy r&eacute;pliqua la Notaire, c&#8217;estoit lui mesme <em>(&hellip;)<\/em>&raquo;<br \/>\n<em>Le Passe-partout du Caquet ds caquets de la nouvelle accouch&eacute;e<\/em> (Caquets, 5e journ&eacute;e), p.25.<br \/>\n&#8211; <strong>1777 <\/strong>: [&agrave; propos des Proverbes dramatiques de Madame Delaisse, publi&eacute;s &laquo;chez la veuve Duchesne, Libraresse, rue Saint-Jacques, au Temple du Go&ucirc;t; et chez l&#8217;Auteur, au Luxembourg&raquo;]<br \/>\n&laquo;Permettez-moi de vous dire, Madame la Comtesse, que j&#8217;aurais voulu que Madame Delaisse e&ucirc;t mis chez l&#8217;Autrice, comme j&#8217;ai mis Libraresse. Ces qualifications ne sont pas approuv&eacute;es, il est vrai, par l&#8217;Acad&eacute;mie Fran&ccedil;aise, mais elles n&#8217;en sont pas moins bonnes et significatives; d&#8217;ailleurs l&#8217;usage les autorise: car nous disons tous les jours &agrave; Paris, une <strong>Notaresse<\/strong>, une Commissaresse, une Libraresse, etc.&raquo;<br \/>\nDe Coudray, &laquo;Annonces et Extraits des Ouvrages dramatiques, ou relatifs &agrave; cet Art&raquo;, <em>Correspondances dramatiques<\/em>, Tome I, Lettre XIV <em>(en r&eacute;alit&eacute;, Lettre XVI)<\/em>, 1er juin 1777, p.257-258.<br \/>\n&#8211;<strong>vers 1873 <\/strong>: &laquo; Mon Cher Vieux, Examine ces croquis o&ugrave; l&rsquo;Art dans une juste mesure s&rsquo;unit &agrave; la Nature &amp; tu verras que le &quot;dessin de Castel&quot; est &quot;sur le Chevalet !&quot; &ndash; Cela suffit ! je ne t&rsquo;en &eacute;cris pas davantage. Je continue &agrave; vaguer avec les plantes de mauvaise vie, je trousse les noires jusquiames (Hyoscyamus Niger ! Sola&eacute;es ! Calice Campanule, corolle infundibuliforme ! Capsule biloculaire fleurs en grappes scorpio&iuml;des ! Ah !) &amp; je fesse les mandragores dans les coins ombreux. &ndash; Je bois le lait des ch&egrave;vres &amp; le soir je danse en rond &agrave; moi tout seul &agrave; la douce voix de Polemon qui chante la femme &agrave; barbe &ndash; barbata ! &amp; Marie-Jos&egrave;phe fuit ad salopette ! Demain Orts, Herman &amp; sa dame flanqu&eacute;s de Franz Servais &amp; de Mme Melot &ndash; <strong>notaresse <\/strong>aimable, &ndash; viennent d&icirc;ner au castel di Thoz&eacute;e, &ndash; nous allons d&eacute;terrer les 42 qui font r&ecirc;ver ! Comme c&rsquo;est b&ecirc;te que tu ne sois pas l&agrave; avec ce tuberculeux de Dommartin ! A propos ce proboscidien a oubli&eacute; son nez chez moi. Ce n&rsquo;est pas que &ccedil;a soit sale mais cela tient de la place, et puis cela ronfle tout seul !!! Je lui renverrai son proboscide muscl&eacute; par la petite vitesse. Je t&rsquo;embrasse &amp; je t&rsquo;enverrai la Machine Castel dans deux ou trois jours, vrai ! Ton vieux F&eacute;ly &raquo; [cette Mme M&eacute;lot serait peut-&ecirc;tre Marie Capelle, &eacute;pouse de l&rsquo;avocat namurois Ernest M&eacute;lot, futur ministre et bourgmestre de Namur].<\/span><\/div>\n<div class=\"corpsTexte\" style=\"text-align: justify;\"><span style=\"font-size: small;\">Lettre de F&eacute;licien Rops &agrave; L&eacute;on Dommartin, s.l., s.d.<\/span><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-size: small;\"><br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOMS PROPRES &#8211; Certains hommes prennent le nom de leur femme. &#8212; XVe si&egrave;cle : Guillaume de l&#8217;Aire, de Tignac dans l&#8217;Ari&egrave;ge, &laquo;prit femme &agrave; Lordat, et &agrave; cause de [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":2804,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":[],"_tribe_ticket_has_attendee_info_fields":false},"translation":{"provider":"WPGlobus","version":"3.0.0","language":"en","enabled_languages":["fr","en"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/pages\/2816"}],"collection":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/comments?post=2816"}],"version-history":[{"count":0,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/pages\/2816\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/pages\/2804"}],"wp:attachment":[{"href":"https:\/\/ancien.siefar.org\/en\/wp-json\/wp\/v2\/media?parent=2816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}